{"id":711585,"date":"2019-05-23T16:10:34","date_gmt":"2019-05-23T16:10:34","guid":{"rendered":"https:\/\/vestigaconsultores.com\/?p=711585"},"modified":"2021-05-12T16:16:29","modified_gmt":"2021-05-12T16:16:29","slug":"google-vs-huawei-la-otra-guerra-de-trump","status":"publish","type":"post","link":"https:\/\/vestigaconsultores.com\/en\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/","title":{"rendered":"Google Vs. Huawei, la otra guerra de Trump"},"content":{"rendered":"<p>23 de mayo de 2019. Estados Unidos y China protagonizan un nuevo cap\u00edtulo en su guerra comercial tras el veto presidencial a Huawei. \u00bfQu\u00e9 significa? Que estos tel\u00e9fonos podr\u00edan quedarse sin sistema operativo Android. Situaci\u00f3n que tiene a millones de usuarios preocupados, ante el riesgo de que sus dispositivos dejen de funcionar en el futuro.<\/p>\n<p>Huawei se comprometi\u00f3 a desarrollar un nuevo sistema operativo si el bloqueo estadounidense se da de manera definitiva. Sin embargo, Carlos Estrada, consultor \u00a0de VESTIGA, considera que el gran riesgo es que esta plataforma no cuente con mecanismos suficientes para proteger los datos de los millones de usuarios en el mundo.<\/p>\n<p>&nbsp;<\/p>\n<h3>Lee la nota completa de <a href=\"https:\/\/www.reporteindigo.com\/reporte\/la-otra-guerra-por-el-poder-huawei-comercio-tecnologia-veto-impacto-veto-trump\/\"><em><u>Reporte \u00cdndigo<\/u><\/em><\/a>, para la cual entrevistaron a Carlos Estrada, encargado de seguridad cibern\u00e9tica de VESTIGA.<\/h3>","protected":false},"excerpt":{"rendered":"<p>23 de mayo de 2019. Estados Unidos y China protagonizan un nuevo cap\u00edtulo en su guerra comercial tras el veto presidencial a Huawei. \u00bfQu\u00e9 significa? Que estos tel\u00e9fonos podr\u00edan quedarse sin sistema operativo Android. Situaci\u00f3n que tiene a millones de usuarios preocupados, ante el riesgo de que sus dispositivos dejen [&hellip;]<\/p>","protected":false},"author":1,"featured_media":711586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[31],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Google Vs. Huawei, la otra guerra de Trump - Vestiga Consultores<\/title>\n<meta name=\"description\" content=\"Huawei, nuevo cap\u00edtulo de la guerra comercial entre Estados Unidos y China que amenaza los datos personales.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vestigaconsultores.com\/en\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Vs. Huawei, la otra guerra de Trump - Vestiga Consultores\" \/>\n<meta property=\"og:description\" content=\"Huawei, nuevo cap\u00edtulo de la guerra comercial entre Estados Unidos y China que amenaza los datos personales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vestigaconsultores.com\/en\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Vestiga Consultores\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-23T16:10:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-12T16:16:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/Huawei-1024x731.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vestigaconsultores.com\/#website\",\"url\":\"https:\/\/vestigaconsultores.com\/\",\"name\":\"Vestiga Consultores\",\"description\":\"Consultor&iacute;a de Riesgo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/vestigaconsultores.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/Huawei.png\",\"contentUrl\":\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/Huawei.png\",\"width\":2000,\"height\":1428,\"caption\":\"Preocupa a millones de usuarios de Huawei que sus dispositivos dejen de funcionar en el futuro.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/#webpage\",\"url\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\",\"name\":\"Google Vs. Huawei, la otra guerra de Trump - Vestiga Consultores\",\"isPartOf\":{\"@id\":\"https:\/\/vestigaconsultores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/#primaryimage\"},\"datePublished\":\"2019-05-23T16:10:34+00:00\",\"dateModified\":\"2021-05-12T16:16:29+00:00\",\"author\":{\"@id\":\"https:\/\/vestigaconsultores.com\/#\/schema\/person\/a5b1dafc37198f04ef09456e367b0e33\"},\"description\":\"Huawei, nuevo cap\\u00edtulo de la guerra comercial entre Estados Unidos y China que amenaza los datos personales.\",\"breadcrumb\":{\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/\",\"url\":\"https:\/\/vestigaconsultores.com\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\",\"url\":\"https:\/\/vestigaconsultores.com\/insights\/google-vs-huawei-la-otra-guerra-de-trump\/\",\"name\":\"Google Vs. Huawei, la otra guerra de Trump\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vestigaconsultores.com\/#\/schema\/person\/a5b1dafc37198f04ef09456e367b0e33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/vestigaconsultores.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dcc4ac78c278dd7c47190d2c936a5501?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dcc4ac78c278dd7c47190d2c936a5501?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/vestigaconsultores.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711585"}],"collection":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/comments?post=711585"}],"version-history":[{"count":1,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711585\/revisions"}],"predecessor-version":[{"id":711587,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711585\/revisions\/711587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/media\/711586"}],"wp:attachment":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/media?parent=711585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/categories?post=711585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/tags?post=711585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}