{"id":711588,"date":"2019-06-24T16:22:07","date_gmt":"2019-06-24T16:22:07","guid":{"rendered":"https:\/\/vestigaconsultores.com\/?p=711588"},"modified":"2021-05-12T16:29:56","modified_gmt":"2021-05-12T16:29:56","slug":"criptoconquista-mundial","status":"publish","type":"post","link":"https:\/\/vestigaconsultores.com\/en\/insights\/criptoconquista-mundial\/","title":{"rendered":"Criptoconquista mundial"},"content":{"rendered":"<p>24 de junio de 2019. La llegada de la criptomoneda Libra podr\u00eda cambiar el sistema financiero global. Si bien no representa una amenaza para otras criptomonedas, existe la posibilidad de que se convierta en el enemigo de las monedas tradicionales. Ello pone en juego su existencia.<\/p>\n<p>Libra tendr\u00e1 un nip de activos financieros que le dar\u00e1 una estabilidad muy fuerte y una volatilidad muy baja a diferencia de las otras criptomonedas e incluso los bitcoins.<\/p>\n<p>Carlos Estrada, encargado de seguridad cibern\u00e9tica en VESTIGA, asegura que este anuncio fue una sorpresa para todos, incluso para las fintech, ya que al principio se imaginaron que solo iba a ser una r\u00e9plica del d\u00f3lar, pero no fue as\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<h3>Lee la nota completa de <a href=\"https:\/\/www.reporteindigo.com\/indigonomics\/criptoconquista-mundial-criptomoneda-libra-facebook-cambio-sistema-financiero\/\"><em><u>Reporte \u00cdndigo<\/u><\/em><\/a>, para la cual entrevistaron a Carlos Estrada, encargado de seguridad cibern\u00e9tica de VESTIGA.<\/h3>","protected":false},"excerpt":{"rendered":"<p>24 de junio de 2019. La llegada de la criptomoneda Libra podr\u00eda cambiar el sistema financiero global. Si bien no representa una amenaza para otras criptomonedas, existe la posibilidad de que se convierta en el enemigo de las monedas tradicionales. Ello pone en juego su existencia. Libra tendr\u00e1 un nip [&hellip;]<\/p>","protected":false},"author":1,"featured_media":711589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[31],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Criptoconquista mundial - Vestiga Consultores<\/title>\n<meta name=\"description\" content=\"La criptomoneda Libra podr\u00eda cambiar el sistema financiero global, pues es posible que se convierta en enemigo de las monedas tradicionales.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vestigaconsultores.com\/en\/insights\/criptoconquista-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Criptoconquista mundial - Vestiga Consultores\" \/>\n<meta property=\"og:description\" content=\"La criptomoneda Libra podr\u00eda cambiar el sistema financiero global, pues es posible que se convierta en enemigo de las monedas tradicionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vestigaconsultores.com\/en\/insights\/criptoconquista-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"Vestiga Consultores\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-24T16:22:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-12T16:29:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/criptomoneda-Libra-1024x731.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vestigaconsultores.com\/#website\",\"url\":\"https:\/\/vestigaconsultores.com\/\",\"name\":\"Vestiga Consultores\",\"description\":\"Consultor&iacute;a de Riesgo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/vestigaconsultores.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/criptomoneda-Libra.png\",\"contentUrl\":\"https:\/\/vestigaconsultores.com\/wp-content\/uploads\/2021\/05\/criptomoneda-Libra.png\",\"width\":2000,\"height\":1428,\"caption\":\"Existe la posibilidad de que la criptomoneda Libra se convierta en el enemigo de las monedas tradicionales.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/#webpage\",\"url\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/\",\"name\":\"Criptoconquista mundial - Vestiga Consultores\",\"isPartOf\":{\"@id\":\"https:\/\/vestigaconsultores.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/#primaryimage\"},\"datePublished\":\"2019-06-24T16:22:07+00:00\",\"dateModified\":\"2021-05-12T16:29:56+00:00\",\"author\":{\"@id\":\"https:\/\/vestigaconsultores.com\/#\/schema\/person\/a5b1dafc37198f04ef09456e367b0e33\"},\"description\":\"La criptomoneda Libra podr\\u00eda cambiar el sistema financiero global, pues es posible que se convierta en enemigo de las monedas tradicionales.\",\"breadcrumb\":{\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/\",\"url\":\"https:\/\/vestigaconsultores.com\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/\",\"url\":\"https:\/\/vestigaconsultores.com\/insights\/criptoconquista-mundial\/\",\"name\":\"Criptoconquista mundial\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vestigaconsultores.com\/#\/schema\/person\/a5b1dafc37198f04ef09456e367b0e33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/vestigaconsultores.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dcc4ac78c278dd7c47190d2c936a5501?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dcc4ac78c278dd7c47190d2c936a5501?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/vestigaconsultores.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711588"}],"collection":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/comments?post=711588"}],"version-history":[{"count":2,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711588\/revisions"}],"predecessor-version":[{"id":711591,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/posts\/711588\/revisions\/711591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/media\/711589"}],"wp:attachment":[{"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/media?parent=711588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/categories?post=711588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vestigaconsultores.com\/en\/wp-json\/wp\/v2\/tags?post=711588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}